{"id":1163,"count":2,"description":"","link":"https:\/\/www.crossroadsinitiative.com\/es\/category\/temas\/etica\/","name":"\u00c9tica","slug":"etica","taxonomy":"category","parent":1097,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00c9tica Archives - Crossroads Initiative<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.crossroadsinitiative.com\/es\/category\/temas\/etica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9tica Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.crossroadsinitiative.com\/es\/category\/temas\/etica\/\" \/>\n<meta property=\"og:site_name\" content=\"Crossroads Initiative\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.crossroadsinitiative.com\/wp-content\/uploads\/2016\/02\/Crossroads-FacebookGrab.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.crossroadsinitiative.com\\\/es\\\/category\\\/temas\\\/etica\\\/\",\"url\":\"https:\\\/\\\/www.crossroadsinitiative.com\\\/es\\\/category\\\/temas\\\/etica\\\/\",\"name\":\"\u00c9tica Archives - Crossroads Initiative\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.crossroadsinitiative.com\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.crossroadsinitiative.com\\\/es\\\/category\\\/temas\\\/etica\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.crossroadsinitiative.com\\\/es\\\/category\\\/temas\\\/etica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.crossroadsinitiative.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Temas\",\"item\":\"https:\\\/\\\/www.crossroadsinitiative.com\\\/es\\\/category\\\/temas\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00c9tica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.crossroadsinitiative.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.crossroadsinitiative.com\\\/it\\\/\",\"name\":\"Crossroads Initiative\",\"description\":\"The #1 Source for Catholic Resources\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.crossroadsinitiative.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00c9tica Archives - Crossroads Initiative","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.crossroadsinitiative.com\/es\/category\/temas\/etica\/","og_locale":"es_ES","og_type":"article","og_title":"\u00c9tica Archives","og_url":"https:\/\/www.crossroadsinitiative.com\/es\/category\/temas\/etica\/","og_site_name":"Crossroads Initiative","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.crossroadsinitiative.com\/wp-content\/uploads\/2016\/02\/Crossroads-FacebookGrab.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.crossroadsinitiative.com\/es\/category\/temas\/etica\/","url":"https:\/\/www.crossroadsinitiative.com\/es\/category\/temas\/etica\/","name":"\u00c9tica Archives - Crossroads Initiative","isPartOf":{"@id":"https:\/\/www.crossroadsinitiative.com\/it\/#website"},"breadcrumb":{"@id":"https:\/\/www.crossroadsinitiative.com\/es\/category\/temas\/etica\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.crossroadsinitiative.com\/es\/category\/temas\/etica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.crossroadsinitiative.com\/"},{"@type":"ListItem","position":2,"name":"Temas","item":"https:\/\/www.crossroadsinitiative.com\/es\/category\/temas\/"},{"@type":"ListItem","position":3,"name":"\u00c9tica"}]},{"@type":"WebSite","@id":"https:\/\/www.crossroadsinitiative.com\/it\/#website","url":"https:\/\/www.crossroadsinitiative.com\/it\/","name":"Crossroads Initiative","description":"The #1 Source for Catholic Resources","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.crossroadsinitiative.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.crossroadsinitiative.com\/es\/wp-json\/wp\/v2\/categories\/1163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.crossroadsinitiative.com\/es\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.crossroadsinitiative.com\/es\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.crossroadsinitiative.com\/es\/wp-json\/wp\/v2\/categories\/1097"}],"wp:post_type":[{"href":"https:\/\/www.crossroadsinitiative.com\/es\/wp-json\/wp\/v2\/posts?categories=1163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}