{"id":1308,"count":2,"description":"","link":"https:\/\/www.crossroadsinitiative.com\/it\/category\/teologia-it\/grazia\/","name":"Grazia","slug":"grazia","taxonomy":"category","parent":1294,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Grazia Archives - Crossroads Initiative<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.crossroadsinitiative.com\/it\/category\/teologia-it\/grazia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grazia Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.crossroadsinitiative.com\/it\/category\/teologia-it\/grazia\/\" \/>\n<meta property=\"og:site_name\" content=\"Crossroads Initiative\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.crossroadsinitiative.com\/wp-content\/uploads\/2016\/02\/Crossroads-FacebookGrab.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.crossroadsinitiative.com\\\/it\\\/category\\\/teologia-it\\\/grazia\\\/\",\"url\":\"https:\\\/\\\/www.crossroadsinitiative.com\\\/it\\\/category\\\/teologia-it\\\/grazia\\\/\",\"name\":\"Grazia Archives - Crossroads Initiative\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.crossroadsinitiative.com\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.crossroadsinitiative.com\\\/it\\\/category\\\/teologia-it\\\/grazia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.crossroadsinitiative.com\\\/it\\\/category\\\/teologia-it\\\/grazia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.crossroadsinitiative.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Teologia\",\"item\":\"https:\\\/\\\/www.crossroadsinitiative.com\\\/it\\\/category\\\/teologia-it\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Grazia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.crossroadsinitiative.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.crossroadsinitiative.com\\\/it\\\/\",\"name\":\"Crossroads Initiative\",\"description\":\"The #1 Source for Catholic Resources\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.crossroadsinitiative.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Grazia Archives - Crossroads Initiative","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.crossroadsinitiative.com\/it\/category\/teologia-it\/grazia\/","og_locale":"it_IT","og_type":"article","og_title":"Grazia Archives","og_url":"https:\/\/www.crossroadsinitiative.com\/it\/category\/teologia-it\/grazia\/","og_site_name":"Crossroads Initiative","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.crossroadsinitiative.com\/wp-content\/uploads\/2016\/02\/Crossroads-FacebookGrab.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.crossroadsinitiative.com\/it\/category\/teologia-it\/grazia\/","url":"https:\/\/www.crossroadsinitiative.com\/it\/category\/teologia-it\/grazia\/","name":"Grazia Archives - Crossroads Initiative","isPartOf":{"@id":"https:\/\/www.crossroadsinitiative.com\/it\/#website"},"breadcrumb":{"@id":"https:\/\/www.crossroadsinitiative.com\/it\/category\/teologia-it\/grazia\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/www.crossroadsinitiative.com\/it\/category\/teologia-it\/grazia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.crossroadsinitiative.com\/"},{"@type":"ListItem","position":2,"name":"Teologia","item":"https:\/\/www.crossroadsinitiative.com\/it\/category\/teologia-it\/"},{"@type":"ListItem","position":3,"name":"Grazia"}]},{"@type":"WebSite","@id":"https:\/\/www.crossroadsinitiative.com\/it\/#website","url":"https:\/\/www.crossroadsinitiative.com\/it\/","name":"Crossroads Initiative","description":"The #1 Source for Catholic Resources","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.crossroadsinitiative.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.crossroadsinitiative.com\/it\/wp-json\/wp\/v2\/categories\/1308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.crossroadsinitiative.com\/it\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.crossroadsinitiative.com\/it\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.crossroadsinitiative.com\/it\/wp-json\/wp\/v2\/categories\/1294"}],"wp:post_type":[{"href":"https:\/\/www.crossroadsinitiative.com\/it\/wp-json\/wp\/v2\/posts?categories=1308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}